{"id":2325,"date":"2011-03-06T14:22:57","date_gmt":"2011-03-06T13:22:57","guid":{"rendered":"http:\/\/www.schlatter.bosshart.li\/de\/?p=2325"},"modified":"2011-03-06T15:37:51","modified_gmt":"2011-03-06T14:37:51","slug":"bunter-abend-mit-daniel","status":"publish","type":"post","link":"https:\/\/www.schlatter.bosshart.li\/de\/2011\/03\/06\/bunter-abend-mit-daniel\/","title":{"rendered":"Bunter Abend mit Daniel&#8230;"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-thumbnail wp-image-2326\" title=\"IMG_4113\" src=\"https:\/\/www.schlatter.bosshart.li\/de\/wp-content\/uploads\/2011\/03\/IMG_4113-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/p>\n<p>Daniel, ein Landes-Gsp\u00e4ndli auf 4-monatiger S\u00fcdamerika-Reise, begegnete uns zum ersten Mal auf Machu Picchu, als gerade seine Freundin Corinne f\u00fcr 2 Wochen zu Besuch war. 2 Monate sp\u00e4ter trafen wir ihn per Zufall am letzten Abend seiner Reise im Hostel in Buenos Aires wieder! \u00dcber die vergangenen 2 Monate gab es nat\u00fcrlich viel zu berichten und so wurde es sp\u00e4ter und sp\u00e4ter&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel, ein Landes-Gsp\u00e4ndli auf 4-monatiger S\u00fcdamerika-Reise, begegnete uns zum ersten Mal auf Machu Picchu, als gerade seine Freundin Corinne f\u00fcr 2 Wochen zu Besuch war. 2 Monate sp\u00e4ter trafen wir ihn per Zufall am letzten Abend seiner Reise im Hostel &hellip; <a href=\"https:\/\/www.schlatter.bosshart.li\/de\/2011\/03\/06\/bunter-abend-mit-daniel\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[42],"tags":[89,70],"class_list":["post-2325","post","type-post","status-publish","format-standard","hentry","category-begegnungen","tag-argentinien","tag-peru"],"_links":{"self":[{"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/posts\/2325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/comments?post=2325"}],"version-history":[{"count":7,"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/posts\/2325\/revisions"}],"predecessor-version":[{"id":2370,"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/posts\/2325\/revisions\/2370"}],"wp:attachment":[{"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/media?parent=2325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/categories?post=2325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schlatter.bosshart.li\/de\/wp-json\/wp\/v2\/tags?post=2325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}